 {"id":3843,"date":"2026-07-14T16:54:07","date_gmt":"2026-07-14T16:54:07","guid":{"rendered":"https:\/\/thereport.mx\/index.php\/2026\/07\/14\/trump-finalmente-paga-5-6-millones-a-e-jean-carroll-tras-anos-de-retrasos-judiciales\/"},"modified":"2026-07-14T22:54:09","modified_gmt":"2026-07-14T22:54:09","slug":"trump-finalmente-paga-5-6-millones-a-e-jean-carroll-tras-anos-de-retrasos-judiciales","status":"publish","type":"post","link":"https:\/\/thereport.mx\/index.php\/2026\/07\/14\/trump-finalmente-paga-5-6-millones-a-e-jean-carroll-tras-anos-de-retrasos-judiciales\/","title":{"rendered":"Trump finalmente paga 5.6 millones a E. Jean Carroll tras a\u00f1os de retrasos judiciales"},"content":{"rendered":"<p>Despu\u00e9s de m\u00e1s de tres a\u00f1os de disputas legales, Donald Trump entreg\u00f3 el martes 14 de julio de 2026 los m\u00e1s de 5.6 millones de d\u00f3lares que un jurado civil federal le orden\u00f3 pagar a la escritora neoyorquina E. Jean Carroll por abuso sexual y difamaci\u00f3n.  <\/p>\n<p>Este pago incluye el monto original de 5 millones de d\u00f3lares m\u00e1s los intereses acumulados, fondos que hab\u00edan sido retenidos mientras Trump continuaba con su apelaci\u00f3n. La Corte Suprema de Estados Unidos decidi\u00f3 el 29 de junio no revisar el caso, lo que abri\u00f3 la puerta para que Carroll solicitara al tribunal de primera instancia en Manhattan que se hiciera efectivo el pago.  <\/p>\n<p>El juez federal Lewis A. Kaplan, nombrado por Bill Clinton, dictamin\u00f3 el 8 de julio que era momento de que Trump cumpliera con la sentencia, se\u00f1alando que el expresidente &#8220;ha estado retrasando este caso durante a\u00f1os&#8221; y que ya era hora de &#8220;hacer justicia&#8221;.  <\/p>\n<p>La demanda de Carroll se basa en una agresi\u00f3n sexual que habr\u00eda ocurrido en un probador de una tienda departamental en la d\u00e9cada de 1990, y en la difamaci\u00f3n posterior cuando Trump calific\u00f3 sus acusaciones como un &#8220;enga\u00f1o&#8221; en 2022. Aunque Trump ha negado rotundamente las acusaciones y ha cuestionado el veredicto un\u00e1nime del jurado civil de 2023, esta resoluci\u00f3n marca un avance significativo para Carroll.  <\/p>\n<p>Cabe destacar que en un caso separado, un jurado civil de Manhattan otorg\u00f3 a Carroll 83.3 millones de d\u00f3lares en 2024 por difamaci\u00f3n, tras concluir que Trump la desacredit\u00f3 p\u00fablicamente en 2019. Esa apelaci\u00f3n a\u00fan est\u00e1 en proceso.  <\/p>\n<p>Este desenlace pone fin, al menos por ahora, a una larga batalla legal que ha mantenido en vilo a la opini\u00f3n p\u00fablica y que refleja la complejidad de los procesos judiciales en casos de abuso y difamaci\u00f3n contra figuras p\u00fablicas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de m\u00e1s de tres a\u00f1os de disputas legales, Donald Trump entreg\u00f3 el martes 14 de julio de 2026 los m\u00e1s de 5.6 millones de d\u00f3lares que un jurado civil federal le orden\u00f3 pagar a la escritora neoyorquina E. Jean Carroll por abuso sexual y difamaci\u00f3n. Este pago incluye el monto original de 5 millones<\/p>\n<a class=\"read-more\" href=\"https:\/\/thereport.mx\/index.php\/2026\/07\/14\/trump-finalmente-paga-5-6-millones-a-e-jean-carroll-tras-anos-de-retrasos-judiciales\/\">Read More<\/a>","protected":false},"author":1,"featured_media":3842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-3843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"_links":{"self":[{"href":"https:\/\/thereport.mx\/index.php\/wp-json\/wp\/v2\/posts\/3843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thereport.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thereport.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thereport.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thereport.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3843"}],"version-history":[{"count":1,"href":"https:\/\/thereport.mx\/index.php\/wp-json\/wp\/v2\/posts\/3843\/revisions"}],"predecessor-version":[{"id":3844,"href":"https:\/\/thereport.mx\/index.php\/wp-json\/wp\/v2\/posts\/3843\/revisions\/3844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thereport.mx\/index.php\/wp-json\/wp\/v2\/media\/3842"}],"wp:attachment":[{"href":"https:\/\/thereport.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thereport.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thereport.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}